{"id":847,"count":1,"description":"","link":"https:\/\/www.doppeladler.com\/da\/tag\/oesterreichische-offiziersgesellschaft-oeog\/","name":"\u00d6sterreichische Offiziersgesellschaft (\u00d6OG)","slug":"oesterreichische-offiziersgesellschaft-oeog","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00d6sterreichische Offiziersgesellschaft (\u00d6OG) Archives - DOPPELADLER.COM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doppeladler.com\/da\/tag\/oesterreichische-offiziersgesellschaft-oeog\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.doppeladler.com\/da\/tag\/oesterreichische-offiziersgesellschaft-oeog\/\",\"url\":\"https:\/\/www.doppeladler.com\/da\/tag\/oesterreichische-offiziersgesellschaft-oeog\/\",\"name\":\"\u00d6sterreichische Offiziersgesellschaft (\u00d6OG) Archives - DOPPELADLER.COM\",\"isPartOf\":{\"@id\":\"https:\/\/www.doppeladler.com\/da\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.doppeladler.com\/da\/tag\/oesterreichische-offiziersgesellschaft-oeog\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.doppeladler.com\/da\/tag\/oesterreichische-offiziersgesellschaft-oeog\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.doppeladler.com\/da\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00d6sterreichische Offiziersgesellschaft (\u00d6OG)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.doppeladler.com\/da\/#website\",\"url\":\"https:\/\/www.doppeladler.com\/da\/\",\"name\":\"DOPPELADLER.COM\",\"description\":\"Plattform f\u00fcr \u00d6sterreichs Milit\u00e4rgeschichte\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.doppeladler.com\/da\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00d6sterreichische Offiziersgesellschaft (\u00d6OG) Archives - DOPPELADLER.COM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doppeladler.com\/da\/tag\/oesterreichische-offiziersgesellschaft-oeog\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.doppeladler.com\/da\/tag\/oesterreichische-offiziersgesellschaft-oeog\/","url":"https:\/\/www.doppeladler.com\/da\/tag\/oesterreichische-offiziersgesellschaft-oeog\/","name":"\u00d6sterreichische Offiziersgesellschaft (\u00d6OG) Archives - DOPPELADLER.COM","isPartOf":{"@id":"https:\/\/www.doppeladler.com\/da\/#website"},"breadcrumb":{"@id":"https:\/\/www.doppeladler.com\/da\/tag\/oesterreichische-offiziersgesellschaft-oeog\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.doppeladler.com\/da\/tag\/oesterreichische-offiziersgesellschaft-oeog\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.doppeladler.com\/da\/"},{"@type":"ListItem","position":2,"name":"\u00d6sterreichische Offiziersgesellschaft (\u00d6OG)"}]},{"@type":"WebSite","@id":"https:\/\/www.doppeladler.com\/da\/#website","url":"https:\/\/www.doppeladler.com\/da\/","name":"DOPPELADLER.COM","description":"Plattform f\u00fcr \u00d6sterreichs Milit\u00e4rgeschichte","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doppeladler.com\/da\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/tags\/847"}],"collection":[{"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/posts?tags=847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}