{"id":4210,"date":"2012-07-09T15:27:32","date_gmt":"2012-07-09T13:27:32","guid":{"rendered":"http:\/\/www.doppeladler.com\/da\/?p=4210"},"modified":"2022-04-19T10:29:51","modified_gmt":"2022-04-19T08:29:51","slug":"militaerluftfahrtausstellung-2012","status":"publish","type":"post","link":"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/","title":{"rendered":"MILIT\u00c4RLUFTFAHRT-AUSSTELLUNG 2012"},"content":{"rendered":"<p style=\"text-align: left;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-4216\" style=\"margin-top: 0px; margin-bottom: 0px;\" title=\"Er\u00f6ffnung der Milit\u00e4rluftfahrtausstellung 2012 als Au\u00dfenstelle des HGMs \u00a9 HGM\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2012\/07\/title-militarluft.jpg\" alt=\"Er\u00f6ffnung der Milit\u00e4rluftfahrtausstellung 2012 als Au\u00dfenstelle des HGMs \u00a9 HGM\" width=\"540\" height=\"200\" srcset=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2012\/07\/title-militarluft.jpg 540w, https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2012\/07\/title-militarluft-300x111.jpg 300w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><span class=\"main-img-text\">Er\u00f6ffnung der Milit\u00e4rluftfahrtausstellung 2012 als Au\u00dfenstelle des HGMs \u00a9 HGM<\/span><\/p>\n<p><strong>Under new management.<\/strong> Auch heuer wieder ist die Milit\u00e4rluftfahrtausstellung am Fliegerhorst Hinterstoisser im steirischen Zeltweg zu besichtigen. Und doch ist vieles anders, denn seit dem Fr\u00fchjahr 2012 wird die Ausstellung als Au\u00dfenstelle des Heeresgeschichtlichen Museums (HGM) gef\u00fchrt.<\/p>\n<p>Die gezeigte Sammlung wurde anl\u00e4sslich des Jubil\u00e4umsjahres 2005 (50 Jahre Bundesheer) vom damaligen Kommando Luftstreitkr\u00e4fte zusammengestellt und war von Beginn an ein gro\u00dfer Wurf. Bereits im ersten Jahr waren nahezu alle ausgemusterten Luftfahrzeugtypen des \u00d6sterreichischen Bundesheeres der 2. Republik (1955-2005) vertreten.<\/p>\n<p>Die Ausstellung war anfangs nur <strong>als tempor\u00e4rer Beitrag zum Jubil\u00e4umsjahr 2005 gedacht<\/strong>. Doch die Zusammenstellung der Exponate im Hangar 8 des Fliegerhorsts entwickelte sich zum Publikumshit. Auch w\u00e4re es angesichts des Errichtungsaufwandes schade gewesen, die Ausstellung wieder aufzul\u00f6sen. Daher wurden die Hangartore auch in den Folgejahren ge\u00f6ffnet und die Ausstellung st\u00e4ndig erweitert (viele Luftfahrzeuge wurden seit 2005 ersatzlos aus dem aktiven Dienst ausgeschieden und bereichern nun die Sammlung). Dies war nur durch das pers\u00f6nliche Engagement vieler Angeh\u00f6riger der Luftstreitkr\u00e4fte und der Mitwirkung und Unterst\u00fctzung des Vereins &#8222;<strong>Gesellschaft zur F\u00f6rderung der \u00d6sterreichischen Luftstreitkr\u00e4fte (GFL)<\/strong>&#8220; m\u00f6glich. Bereits w\u00e4hrend der Airpower 2009 Flugshow wurde der 100.000ste Besucher gez\u00e4hlt.<\/p>\n<p>Doch die bisherige Geschichte der Ausstellung war nicht immer nur rosig. Im Laufe der Jahre gab es immer wieder Ger\u00fcchte um die Aufl\u00f6sung oder Verlegung der Sammlung. Erst 2011 hatte der Tourismusverband Aichfeld rund 10.000 Unterschriften f\u00fcr den Fortbestand der Schau gesammelt, da Ger\u00fcchten zufolge die Ausstellung nach Wien abgesiedelt werden sollte.<\/p>\n<p><strong>Seit Anfang 2012 ist die Milit\u00e4rluftfahrtausstellung in Zeltweg nun offiziell in das Heeresgeschichtlichen Museum eingegliedert<\/strong> und wird als Au\u00dfenstelle betrieben. Somit ist sie Bestandteil eines der \u00e4ltesten und traditionsreichsten Milit\u00e4rmuseen weltweit. An der Location soll sich laut Auskunft des HGM nichts \u00e4ndern. Schon bisher befand sich ein gro\u00dfer Teil der Exponate im Besitz des HGM. Auch die GFL bleibt ein wichtiges Element, um den Ausstellungsbetrieb aufrecht zu erhalten. Es ist daher zu hoffen, dass die einzigartige Ausstellung nun endg\u00fcltig als permanent angesehen werden kann.<\/p>\n<p>Am 4. Juni 2012 erfolgte die feierliche Er\u00f6ffnung der Saison 2012. Auch heuer wieder gibt es einige Neuzug\u00e4nge: ein nachgebauter Lilientalgleiter, ein Segelgleiter SG 38 sowie ein beim \u00d6sterreichischen Bundesheer in Verwendung gewesenes Segelflugzeug Musger MG 19.<\/p>\n<div id=\"penci-post-gallery__84901\" class=\"penci-post-gallery-container justified column-3\" data-height=\"150\" data-margin=\"3\"><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2012\/07\/musik.jpg\" data-cap=\"Er\u00f6ffnung der Ausstellung f\u00fcr Milit\u00e4rluftfahrt am 5. Juni 2012 \u00a9 LuAufklESt\/ZINNER Markus\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2012\/07\/musik.jpg\" alt=\"Er\u00f6ffnung der Ausstellung f\u00fcr Milit\u00e4rluftfahrt am 5. Juni 2012 \u00a9 LuAufklESt\/ZINNER Markus\" title=\"Er\u00f6ffnung der Ausstellung f\u00fcr Milit\u00e4rluftfahrt am 5. Juni 2012 \u00a9 LuAufklESt\/ZINNER Markus\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2012\/07\/helis.jpg\" data-cap=\"Hubschraubertypen AB-204 (links) und AB-206 (rechts) \u00a9 HGM\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2012\/07\/helis.jpg\" alt=\"Hubschraubertypen AB-204 (links) und AB-206 (rechts) \u00a9 HGM\" title=\"Hubschraubertypen AB-204 (links) und AB-206 (rechts) \u00a9 HGM\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2012\/07\/segler.jpg\" data-cap=\"Neuzugang mit der Nr 0443 - Segelflugzeug vom Typ Musger MG 19 \u00a9 HGM\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2012\/07\/segler.jpg\" alt=\"Neuzugang mit der Nr 0443 - Segelflugzeug vom Typ Musger MG 19 \u00a9 HGM\" title=\"Neuzugang mit der Nr 0443 &#8211; Segelflugzeug vom Typ Musger MG 19 \u00a9 HGM\"><\/a><\/div>\n<p>Die auf etwa 6.300 m\u00b2 Ausstellungsfl\u00e4che errichtete Milit\u00e4rluftfahrtausstellung ist in der Halle 8 des Fliegerhorstes Hinterstoisser untergebracht. Neben der Ausstellung der originalen Luftfahrzeuge werden auch Fahrzeuge und Ger\u00e4te der Fliegerabwehrtruppe, des Flugbetriebsdienstes, der Luftaufkl\u00e4rung sowie der Luftfahrttechnik (Triebwerke) gezeigt. Den Link zu unserer Reportage aus den fr\u00fchen Jahren finden Sie am Ende dieses Berichts.<\/p>\n<h2>\u00dcBERSICHT 2012<\/h2>\n<p>Ausstellungssaison 2012: 4. Juni 2012 bis 21. Oktober 2012<br \/>\n\u00d6ffnungszeiten Di. &#8211; So. von 09.00 &#8211; 17.00 Uhr<\/p>\n<p>Eintrittspreise: Normalpreis \u20ac 3,- \/ Erm\u00e4\u00dfigter Eintritt \u20ac 2,- (Erm\u00e4\u00dfigter Eintrittspreis f\u00fcr Studenten, Behinderte, Senioren ab dem 60. Lebensjahr, jeweils nur mit Ausweis)<\/p>\n<p>Freier Eintritt f\u00fcr Personen bis zum vollendeten 19. Lebensjahr, Teilnehmer von Lehrveranstaltungen, Mitglieder der GFL, Mitglieder des Vereins der Freunde des HGM, vom Museumsbund oder ICOM, Schwerkriegsbesch\u00e4digte, Soldaten in Uniform.<\/p>\n<p>Auch bei freiem oder erm\u00e4\u00dfigtem Eintritt ist eine Teilnahme an F\u00fchrungen nur gegen Voranmeldung (siehe Homepage der GFL &#8211; unten) m\u00f6glich.<\/p>\n<p>An jedem ersten Sonntag im Monat ist der Eintritt frei.<\/p>\n<p>Adresse: Fliegerhorst HINTERSTOISSER, Hangar 8; 8740 Zeltweg<br \/>\nZufahrt \u00fcber Bundesstra\u00dfe B 317 (Navi-Eingabe: Bundesstra\u00dfe 14)<\/p>\n<p><iframe src=\"https:\/\/maps.google.at\/maps?hl=de&amp;client=firefox-a&amp;q=Bundesstra%C3%9Fe+14+Zeltweg&amp;ie=UTF8&amp;hq=&amp;hnear=Bundesstra%C3%9Fe+14,+8740+Zeltweg,+Judenburg,+Steiermark&amp;gl=at&amp;t=h&amp;ll=47.194787,14.745626&amp;spn=0.020413,0.046349&amp;z=14&amp;iwloc=A&amp;output=embed\" width=\"540\" height=\"350\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><br \/>\n<small><a style=\"color: #0000ff; text-align: left;\" href=\"https:\/\/maps.google.at\/maps?hl=de&amp;client=firefox-a&amp;q=Bundesstra%C3%9Fe+14+Zeltweg&amp;ie=UTF8&amp;hq=&amp;hnear=Bundesstra%C3%9Fe+14,+8740+Zeltweg,+Judenburg,+Steiermark&amp;gl=at&amp;t=h&amp;ll=47.194787,14.745626&amp;spn=0.020413,0.046349&amp;z=14&amp;iwloc=A&amp;source=embed\">Gr\u00f6\u00dfere Kartenansicht<\/a><\/small><\/p>\n<p><strong>Weiterf\u00fchrende Links<\/strong>:<\/p>\n<ul>\n<li><a title=\"GFL\" href=\"http:\/\/www.luftstreitkraefte.at\/\" target=\"_blank\" rel=\"noopener\">Gesellschaft zur F\u00f6rderung der \u00d6sterreichischen Luftstreitkr\u00e4fte (GFL)<\/a><\/li>\n<li><a title=\"HGM Wien\" href=\"http:\/\/www.hgm.or.at\/\" target=\"_blank\" rel=\"noopener\">Heeresgeschichtliches Museum<\/a><\/li>\n<li><a href=\"http:\/\/www.doppeladler.com\/oebh\/sammlung05.htm\">Unsere Reportage zur Milit\u00e4rluftfahrtausstellung (Archiv) <\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Under new management. Auch heuer wieder ist die Milit\u00e4rluftfahrtausstellung am Fliegerhorst Hinterstoisser im steirischen Zeltweg zu besichtigen. Und doch ist vieles anders, denn seit dem Fr\u00fchjahr 2012 wird die Ausstellung als Au\u00dfenstelle des Heeresgeschichtlichen Museums (HGM) gef\u00fchrt.<\/p>\n","protected":false},"author":1,"featured_media":4216,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,9],"tags":[72,271,164,385,448,81,11,96,46,446,447,423,95],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MILIT\u00c4RLUFTFAHRT-AUSSTELLUNG 2012 | DOPPELADLER.COM<\/title>\n<meta name=\"description\" content=\"Auch heuer wieder ist die Milit\u00e4rluftfahrtausstellung am Fliegerhorst Hinterstoisser im steirischen Zeltweg zu besichtigen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Doppeladler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/\",\"url\":\"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/\",\"name\":\"MILIT\u00c4RLUFTFAHRT-AUSSTELLUNG 2012 | DOPPELADLER.COM\",\"isPartOf\":{\"@id\":\"https:\/\/www.doppeladler.com\/da\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2012\/07\/title-militarluft.jpg\",\"datePublished\":\"2012-07-09T13:27:32+00:00\",\"dateModified\":\"2022-04-19T08:29:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.doppeladler.com\/da\/#\/schema\/person\/232b998b629b89b24a916becce3e9476\"},\"description\":\"Auch heuer wieder ist die Milit\u00e4rluftfahrtausstellung am Fliegerhorst Hinterstoisser im steirischen Zeltweg zu besichtigen.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/#primaryimage\",\"url\":\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2012\/07\/title-militarluft.jpg\",\"contentUrl\":\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2012\/07\/title-militarluft.jpg\",\"width\":\"540\",\"height\":\"200\",\"caption\":\"Er\u00f6ffnung der Milit\u00e4rluftfahrtausstellung 2012 als Au\u00dfenstelle des HGMs \u00a9 HGM\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.doppeladler.com\/da\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MILIT\u00c4RLUFTFAHRT-AUSSTELLUNG 2012\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.doppeladler.com\/da\/#website\",\"url\":\"https:\/\/www.doppeladler.com\/da\/\",\"name\":\"DOPPELADLER.COM\",\"description\":\"Plattform f\u00fcr \u00d6sterreichs Milit\u00e4rgeschichte\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.doppeladler.com\/da\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.doppeladler.com\/da\/#\/schema\/person\/232b998b629b89b24a916becce3e9476\",\"name\":\"Doppeladler\",\"sameAs\":[\"http:\/\/www.doppeladler.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MILIT\u00c4RLUFTFAHRT-AUSSTELLUNG 2012 | DOPPELADLER.COM","description":"Auch heuer wieder ist die Milit\u00e4rluftfahrtausstellung am Fliegerhorst Hinterstoisser im steirischen Zeltweg zu besichtigen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/","twitter_misc":{"Verfasst von":"Doppeladler","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/","url":"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/","name":"MILIT\u00c4RLUFTFAHRT-AUSSTELLUNG 2012 | DOPPELADLER.COM","isPartOf":{"@id":"https:\/\/www.doppeladler.com\/da\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/#primaryimage"},"image":{"@id":"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/#primaryimage"},"thumbnailUrl":"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2012\/07\/title-militarluft.jpg","datePublished":"2012-07-09T13:27:32+00:00","dateModified":"2022-04-19T08:29:51+00:00","author":{"@id":"https:\/\/www.doppeladler.com\/da\/#\/schema\/person\/232b998b629b89b24a916becce3e9476"},"description":"Auch heuer wieder ist die Milit\u00e4rluftfahrtausstellung am Fliegerhorst Hinterstoisser im steirischen Zeltweg zu besichtigen.","breadcrumb":{"@id":"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/#primaryimage","url":"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2012\/07\/title-militarluft.jpg","contentUrl":"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2012\/07\/title-militarluft.jpg","width":"540","height":"200","caption":"Er\u00f6ffnung der Milit\u00e4rluftfahrtausstellung 2012 als Au\u00dfenstelle des HGMs \u00a9 HGM"},{"@type":"BreadcrumbList","@id":"https:\/\/www.doppeladler.com\/da\/oebh\/militaerluftfahrtausstellung-2012\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.doppeladler.com\/da\/"},{"@type":"ListItem","position":2,"name":"MILIT\u00c4RLUFTFAHRT-AUSSTELLUNG 2012"}]},{"@type":"WebSite","@id":"https:\/\/www.doppeladler.com\/da\/#website","url":"https:\/\/www.doppeladler.com\/da\/","name":"DOPPELADLER.COM","description":"Plattform f\u00fcr \u00d6sterreichs Milit\u00e4rgeschichte","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doppeladler.com\/da\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.doppeladler.com\/da\/#\/schema\/person\/232b998b629b89b24a916becce3e9476","name":"Doppeladler","sameAs":["http:\/\/www.doppeladler.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/posts\/4210"}],"collection":[{"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/comments?post=4210"}],"version-history":[{"count":2,"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/posts\/4210\/revisions"}],"predecessor-version":[{"id":17029,"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/posts\/4210\/revisions\/17029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/media\/4216"}],"wp:attachment":[{"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/media?parent=4210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/categories?post=4210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/tags?post=4210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}