{"id":12991,"date":"2018-09-30T20:04:36","date_gmt":"2018-09-30T18:04:36","guid":{"rendered":"http:\/\/www.doppeladler.com\/da\/?p=12991"},"modified":"2019-09-01T23:04:44","modified_gmt":"2019-09-01T21:04:44","slug":"riat-2018-2","status":"publish","type":"post","link":"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/","title":{"rendered":"RIAT 2018 &#8211; Fotoreportage &#8211; Teil 2"},"content":{"rendered":"<p>Hier der 2. Teil unserer Fotoreportage von der Royal International Air Tattoo RIAT 2018 in Fairford.<\/p>\n<h2>IMPRESSIONEN &#8211; TEIL 2<\/h2>\n<div id=\"penci-post-gallery__66035\" class=\"penci-post-gallery-container justified column-3\" data-height=\"150\" data-margin=\"3\"><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-5.jpg\" data-cap=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-5.jpg\" alt=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\" title=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-8.jpg\" data-cap=\"Fokker Dr1 Dreidecker Nachbau 556\/17 in der Bemalung von Leutnant Ludwig &quot;Lutz&quot; Beckmann, Jasta 6, M\u00e4rz 1918 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-8.jpg\" alt=\"Fokker Dr1 Dreidecker Nachbau 556\/17 in der Bemalung von Leutnant Ludwig &quot;Lutz&quot; Beckmann, Jasta 6, M\u00e4rz 1918 \u00a9 Doppeladler.com\" title=\"Fokker Dr1 Dreidecker Nachbau 556\/17 in der Bemalung von Leutnant Ludwig &#8222;Lutz&#8220; Beckmann, Jasta 6, M\u00e4rz 1918 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f35-heritage-6.jpg\" data-cap=\"Lockheed Martin F-35A Lightning II 15-5127; North American P-51D Mustang 413305; Supermarine Spitfire Mk.Vc JG891 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f35-heritage-6.jpg\" alt=\"Lockheed Martin F-35A Lightning II 15-5127; North American P-51D Mustang 413305; Supermarine Spitfire Mk.Vc JG891 \u00a9 Doppeladler.com\" title=\"Lockheed Martin F-35A Lightning II 15-5127; North American P-51D Mustang 413305; Supermarine Spitfire Mk.Vc JG891 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-pl-2.jpg\" data-cap=\"Lockheed Martin F-16C (Block 52) Fighting Falcon 4052 aus Polen \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-pl-2.jpg\" alt=\"Lockheed Martin F-16C (Block 52) Fighting Falcon 4052 aus Polen \u00a9 Doppeladler.com\" title=\"Lockheed Martin F-16C (Block 52) Fighting Falcon 4052 aus Polen \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-22.jpg\" data-cap=\"Red Arrows tanzen Walzer \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-22.jpg\" alt=\"Red Arrows tanzen Walzer \u00a9 Doppeladler.com\" title=\"Red Arrows tanzen Walzer \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/b1-1.jpg\" data-cap=\"Rockwell B-1 B Lancer \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/b1-1.jpg\" alt=\"Rockwell B-1 B Lancer \u00a9 Doppeladler.com\" title=\"Rockwell B-1 B Lancer \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/kustwacht-1.jpg\" data-cap=\"Dornier Do.228-212 PH-CGC der niederl\u00e4ndischen K\u00fcstenwache \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/kustwacht-1.jpg\" alt=\"Dornier Do.228-212 PH-CGC der niederl\u00e4ndischen K\u00fcstenwache \u00a9 Doppeladler.com\" title=\"Dornier Do.228-212 PH-CGC der niederl\u00e4ndischen K\u00fcstenwache \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-17.jpg\" data-cap=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-17.jpg\" alt=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\" title=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f18-ca-11.jpg\" data-cap=\"McDonnell-Douglas CF-188A Hornet 776 aus Kanada \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f18-ca-11.jpg\" alt=\"McDonnell-Douglas CF-188A Hornet 776 aus Kanada \u00a9 Doppeladler.com\" title=\"McDonnell-Douglas CF-188A Hornet 776 aus Kanada \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-bel-5.jpg\" data-cap=\"Lockheed F-16 MLU &quot;Dark Falcon&quot; FA101 der belgischen Luftwaffe \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-bel-5.jpg\" alt=\"Lockheed F-16 MLU &quot;Dark Falcon&quot; FA101 der belgischen Luftwaffe \u00a9 Doppeladler.com\" title=\"Lockheed F-16 MLU &#8222;Dark Falcon&#8220; FA101 der belgischen Luftwaffe \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-27.jpg\" data-cap=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-27.jpg\" alt=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\" title=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/lancaster-5.jpg\" data-cap=\"Avro Lancaster B.1 PA474 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/lancaster-5.jpg\" alt=\"Avro Lancaster B.1 PA474 \u00a9 Doppeladler.com\" title=\"Avro Lancaster B.1 PA474 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f35-us-12a.jpg\" data-cap=\"Lockheed Martin F-35A Lightning II 15-5127 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f35-us-12a.jpg\" alt=\"Lockheed Martin F-35A Lightning II 15-5127 \u00a9 Doppeladler.com\" title=\"Lockheed Martin F-35A Lightning II 15-5127 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/frecce-17.jpg\" data-cap=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/frecce-17.jpg\" alt=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\" title=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-bel-3.jpg\" data-cap=\"Lockheed F-16 MLU &quot;Dark Falcon&quot; FA101 der belgischen Luftwaffe \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-bel-3.jpg\" alt=\"Lockheed F-16 MLU &quot;Dark Falcon&quot; FA101 der belgischen Luftwaffe \u00a9 Doppeladler.com\" title=\"Lockheed F-16 MLU &#8222;Dark Falcon&#8220; FA101 der belgischen Luftwaffe \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/gripen-5.jpg\" data-cap=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/gripen-5.jpg\" alt=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\" title=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-13.jpg\" data-cap=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-13.jpg\" alt=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\" title=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/dambusters-4.jpg\" data-cap=\"Dambusters: Lockheed Martin F-35B Lightning II und Lancaster-Bomber \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/dambusters-4.jpg\" alt=\"Dambusters: Lockheed Martin F-35B Lightning II und Lancaster-Bomber \u00a9 Doppeladler.com\" title=\"Dambusters: Lockheed Martin F-35B Lightning II und Lancaster-Bomber \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-8.jpg\" data-cap=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-8.jpg\" alt=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\" title=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f35-gb-2b.jpg\" data-cap=\"Lockheed Martin F-35B Lightning II ZMI45 der Royal Air Force \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f35-gb-2b.jpg\" alt=\"Lockheed Martin F-35B Lightning II ZMI45 der Royal Air Force \u00a9 Doppeladler.com\" title=\"Lockheed Martin F-35B Lightning II ZMI45 der Royal Air Force \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-11b.jpg\" data-cap=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-11b.jpg\" alt=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\" title=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-6.jpg\" data-cap=\"Supermarine Spitfire PR.XIX - PS915 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-6.jpg\" alt=\"Supermarine Spitfire PR.XIX - PS915 \u00a9 Doppeladler.com\" title=\"Supermarine Spitfire PR.XIX &#8211; PS915 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-5.jpg\" data-cap=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-5.jpg\" alt=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\" title=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/lancaster-4.jpg\" data-cap=\"Avro Lancaster B.1 PA474 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/lancaster-4.jpg\" alt=\"Avro Lancaster B.1 PA474 \u00a9 Doppeladler.com\" title=\"Avro Lancaster B.1 PA474 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/m346fa-1.jpg\" data-cap=\"Leonardo M-346 Master X-AJT, ausger\u00fcstet als M-346 FA Demonstrator (Fighter Attack). Die M-346 gilt als Wunschkandidat f\u00fcr die Saab 105 Nachfolge \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/m346fa-1.jpg\" alt=\"Leonardo M-346 Master X-AJT, ausger\u00fcstet als M-346 FA Demonstrator (Fighter Attack). Die M-346 gilt als Wunschkandidat f\u00fcr die Saab 105 Nachfolge \u00a9 Doppeladler.com\" title=\"Leonardo M-346 Master X-AJT, ausger\u00fcstet als M-346 FA Demonstrator (Fighter Attack). Die M-346 gilt als Wunschkandidat f\u00fcr die Saab 105 Nachfolge \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f35-heritage-8.jpg\" data-cap=\"USAF Heritage Flight Team \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f35-heritage-8.jpg\" alt=\"USAF Heritage Flight Team \u00a9 Doppeladler.com\" title=\"USAF Heritage Flight Team \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/mirage-5.jpg\" data-cap=\"Dassault Mirage 2000D 3-XY Couteau Delta Display Team \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/mirage-5.jpg\" alt=\"Dassault Mirage 2000D 3-XY Couteau Delta Display Team \u00a9 Doppeladler.com\" title=\"Dassault Mirage 2000D 3-XY Couteau Delta Display Team \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-21.jpg\" data-cap=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-21.jpg\" alt=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\" title=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/a400m-5.jpg\" data-cap=\"Airbus A400M Atlas \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/a400m-5.jpg\" alt=\"Airbus A400M Atlas \u00a9 Doppeladler.com\" title=\"Airbus A400M Atlas \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-16.jpg\" data-cap=\"Dassault Rafale M (6) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-16.jpg\" alt=\"Dassault Rafale M (6) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\" title=\"Dassault Rafale M (6) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/frecce-9.jpg\" data-cap=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/frecce-9.jpg\" alt=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\" title=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f18-ca-3.jpg\" data-cap=\"McDonnell-Douglas CF-188A Hornet 776 aus Kanada \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f18-ca-3.jpg\" alt=\"McDonnell-Douglas CF-188A Hornet 776 aus Kanada \u00a9 Doppeladler.com\" title=\"McDonnell-Douglas CF-188A Hornet 776 aus Kanada \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/dc3-1.jpg\" data-cap=\"Douglas DC-3 \/ C-47A ZA947 des BBMF \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/dc3-1.jpg\" alt=\"Douglas DC-3 \/ C-47A ZA947 des BBMF \u00a9 Doppeladler.com\" title=\"Douglas DC-3 \/ C-47A ZA947 des BBMF \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f35-gb-6.jpg\" data-cap=\"Lockheed Martin F-35B Lightning II ZMI45 der Royal Air Force \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f35-gb-6.jpg\" alt=\"Lockheed Martin F-35B Lightning II ZMI45 der Royal Air Force \u00a9 Doppeladler.com\" title=\"Lockheed Martin F-35B Lightning II ZMI45 der Royal Air Force \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/gripen-1.jpg\" data-cap=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/gripen-1.jpg\" alt=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\" title=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f18-sui-5.jpg\" data-cap=\"McDonnell Douglas F\/A-18C Hornet J-5010 aus der Schweiz \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f18-sui-5.jpg\" alt=\"McDonnell Douglas F\/A-18C Hornet J-5010 aus der Schweiz \u00a9 Doppeladler.com\" title=\"McDonnell Douglas F\/A-18C Hornet J-5010 aus der Schweiz \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-6.jpg\" data-cap=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-6.jpg\" alt=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\" title=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/hawk-2.jpg\" data-cap=\"BAe Systems Hawk 128 T.2 Jettrainer ZK032. Auch ein Kandidat f\u00fcr die Saab 105 Nachfolge \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/hawk-2.jpg\" alt=\"BAe Systems Hawk 128 T.2 Jettrainer ZK032. Auch ein Kandidat f\u00fcr die Saab 105 Nachfolge \u00a9 Doppeladler.com\" title=\"BAe Systems Hawk 128 T.2 Jettrainer ZK032. Auch ein Kandidat f\u00fcr die Saab 105 Nachfolge \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/mirage-9.jpg\" data-cap=\"Dassault Mirage 2000D des Couteau Delta Display Teams \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/mirage-9.jpg\" alt=\"Dassault Mirage 2000D des Couteau Delta Display Teams \u00a9 Doppeladler.com\" title=\"Dassault Mirage 2000D des Couteau Delta Display Teams \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/jordanien-4.jpg\" data-cap=\"Royal Jordanian Falcons auf Extra 300LX \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/jordanien-4.jpg\" alt=\"Royal Jordanian Falcons auf Extra 300LX \u00a9 Doppeladler.com\" title=\"Royal Jordanian Falcons auf Extra 300LX \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ef-static-2.jpg\" data-cap=\"Britische Eurofighter Typhoon FGR.4 und Tornado GR.4 in der Flightline \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ef-static-2.jpg\" alt=\"Britische Eurofighter Typhoon FGR.4 und Tornado GR.4 in der Flightline \u00a9 Doppeladler.com\" title=\"Britische Eurofighter Typhoon FGR.4 und Tornado GR.4 in der Flightline \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-gr-6.jpg\" data-cap=\"Lockheed Martin F-16C Fighting Falcon 520 aus Griechenland \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-gr-6.jpg\" alt=\"Lockheed Martin F-16C Fighting Falcon 520 aus Griechenland \u00a9 Doppeladler.com\" title=\"Lockheed Martin F-16C Fighting Falcon 520 aus Griechenland \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f18-sui-6.jpg\" data-cap=\"McDonnell Douglas F\/A-18C Hornet J-5010 aus der Schweiz \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f18-sui-6.jpg\" alt=\"McDonnell Douglas F\/A-18C Hornet J-5010 aus der Schweiz \u00a9 Doppeladler.com\" title=\"McDonnell Douglas F\/A-18C Hornet J-5010 aus der Schweiz \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-26.jpg\" data-cap=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-26.jpg\" alt=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\" title=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/mq8c-1.jpg\" data-cap=\"Northrop Grumman MQ\u22128C Fire Scout Drohne aus Point Mugu Naval Air Station der US Navy \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/mq8c-1.jpg\" alt=\"Northrop Grumman MQ\u22128C Fire Scout Drohne aus Point Mugu Naval Air Station der US Navy \u00a9 Doppeladler.com\" title=\"Northrop Grumman MQ\u22128C Fire Scout Drohne aus Point Mugu Naval Air Station der US Navy \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-pl-13.jpg\" data-cap=\"Lockheed Martin F-16C (Block 52) Fighting Falcon 4052 aus Polen \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-pl-13.jpg\" alt=\"Lockheed Martin F-16C (Block 52) Fighting Falcon 4052 aus Polen \u00a9 Doppeladler.com\" title=\"Lockheed Martin F-16C (Block 52) Fighting Falcon 4052 aus Polen \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/c27j-2.jpg\" data-cap=\"Alenia Aermacchi C-27J Spartan RS-50 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/c27j-2.jpg\" alt=\"Alenia Aermacchi C-27J Spartan RS-50 \u00a9 Doppeladler.com\" title=\"Alenia Aermacchi C-27J Spartan RS-50 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/Hurricane-4.jpg\" data-cap=\"Hawker Hurricane IIC LF363 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/Hurricane-4.jpg\" alt=\"Hawker Hurricane IIC LF363 \u00a9 Doppeladler.com\" title=\"Hawker Hurricane IIC LF363 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f35-heritage-2.jpg\" data-cap=\"Lockheed Martin F-35A Lightning II 15-5127; North American P-51D Mustang 413305; Supermarine Spitfire Mk.Vc JG891 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f35-heritage-2.jpg\" alt=\"Lockheed Martin F-35A Lightning II 15-5127; North American P-51D Mustang 413305; Supermarine Spitfire Mk.Vc JG891 \u00a9 Doppeladler.com\" title=\"Lockheed Martin F-35A Lightning II 15-5127; North American P-51D Mustang 413305; Supermarine Spitfire Mk.Vc JG891 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/heli-3.jpg\" data-cap=\"Westland Whirlwind HAR.2 SAR Hubschrauber XJ729 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/heli-3.jpg\" alt=\"Westland Whirlwind HAR.2 SAR Hubschrauber XJ729 \u00a9 Doppeladler.com\" title=\"Westland Whirlwind HAR.2 SAR Hubschrauber XJ729 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/gripen-8.jpg\" data-cap=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/gripen-8.jpg\" alt=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\" title=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-22.jpg\" data-cap=\"Royal Aircraft Factory SE-5A Replica G-BUOD B595 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-22.jpg\" alt=\"Royal Aircraft Factory SE-5A Replica G-BUOD B595 \u00a9 Doppeladler.com\" title=\"Royal Aircraft Factory SE-5A Replica G-BUOD B595 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/nh90-6.jpg\" data-cap=\"NH Industries NH90 TTH aus Finnland NH-219 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/nh90-6.jpg\" alt=\"NH Industries NH90 TTH aus Finnland NH-219 \u00a9 Doppeladler.com\" title=\"NH Industries NH90 TTH aus Finnland NH-219 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-17.jpg\" data-cap=\"Supermarine Spitfire LF Mk IXc - MK356 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-17.jpg\" alt=\"Supermarine Spitfire LF Mk IXc - MK356 \u00a9 Doppeladler.com\" title=\"Supermarine Spitfire LF Mk IXc &#8211; MK356 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f35-us-14.jpg\" data-cap=\"Lockheed Martin F-35A Lightning II 15-5127 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f35-us-14.jpg\" alt=\"Lockheed Martin F-35A Lightning II 15-5127 \u00a9 Doppeladler.com\" title=\"Lockheed Martin F-35A Lightning II 15-5127 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f18-sui-8.jpg\" data-cap=\"McDonnell Douglas F\/A-18C Hornet J-5010 aus der Schweiz \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f18-sui-8.jpg\" alt=\"McDonnell Douglas F\/A-18C Hornet J-5010 aus der Schweiz \u00a9 Doppeladler.com\" title=\"McDonnell Douglas F\/A-18C Hornet J-5010 aus der Schweiz \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-9.jpg\" data-cap=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-9.jpg\" alt=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\" title=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/oldtimer-1.jpg\" data-cap=\"De Havilland DH-82A Tiger Moth K-2585 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/oldtimer-1.jpg\" alt=\"De Havilland DH-82A Tiger Moth K-2585 \u00a9 Doppeladler.com\" title=\"De Havilland DH-82A Tiger Moth K-2585 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/a400m-1.jpg\" data-cap=\"Airbus A400M Atlas \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/a400m-1.jpg\" alt=\"Airbus A400M Atlas \u00a9 Doppeladler.com\" title=\"Airbus A400M Atlas \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ef-uk-12.jpg\" data-cap=\"Eurofighter Typhoon FGR.4 ZK318 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ef-uk-12.jpg\" alt=\"Eurofighter Typhoon FGR.4 ZK318 \u00a9 Doppeladler.com\" title=\"Eurofighter Typhoon FGR.4 ZK318 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/frecce-19.jpg\" data-cap=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/frecce-19.jpg\" alt=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\" title=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-11.jpg\" data-cap=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-11.jpg\" alt=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\" title=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ospey-1.jpg\" data-cap=\"USAF Bell-Boeing CV-22B Osprey 08-0050. Leider aufgrund eines Defekts nur am Boden zu sehen \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ospey-1.jpg\" alt=\"USAF Bell-Boeing CV-22B Osprey 08-0050. Leider aufgrund eines Defekts nur am Boden zu sehen \u00a9 Doppeladler.com\" title=\"USAF Bell-Boeing CV-22B Osprey 08-0050. Leider aufgrund eines Defekts nur am Boden zu sehen \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-7.jpg\" data-cap=\"Supermarine Spitfire PR.XIX - PS915 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-7.jpg\" alt=\"Supermarine Spitfire PR.XIX - PS915 \u00a9 Doppeladler.com\" title=\"Supermarine Spitfire PR.XIX &#8211; PS915 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/patrulla-4.jpg\" data-cap=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/patrulla-4.jpg\" alt=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\" title=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/b2-5b.jpg\" data-cap=\"Northrop Grumman B-2 Spirit &quot;Spirit of New York&quot; \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/b2-5b.jpg\" alt=\"Northrop Grumman B-2 Spirit &quot;Spirit of New York&quot; \u00a9 Doppeladler.com\" title=\"Northrop Grumman B-2 Spirit &#8222;Spirit of New York&#8220; \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/patrulla-16.jpg\" data-cap=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/patrulla-16.jpg\" alt=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\" title=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f18-ca-5.jpg\" data-cap=\"McDonnell-Douglas CF-188A Hornet 776 im &quot;60 Jahre NORAD&quot; Anstrich \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f18-ca-5.jpg\" alt=\"McDonnell-Douglas CF-188A Hornet 776 im &quot;60 Jahre NORAD&quot; Anstrich \u00a9 Doppeladler.com\" title=\"McDonnell-Douglas CF-188A Hornet 776 im &#8222;60 Jahre NORAD&#8220; Anstrich \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-4.jpg\" data-cap=\"PC-7 Team und F\/A-18C Hornet der Schweizer Luftwaffe \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-4.jpg\" alt=\"PC-7 Team und F\/A-18C Hornet der Schweizer Luftwaffe \u00a9 Doppeladler.com\" title=\"PC-7 Team und F\/A-18C Hornet der Schweizer Luftwaffe \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-4.jpg\" data-cap=\"Das Great War Display Team mit ihren WW1 Flugzeug-Nachbauten \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-4.jpg\" alt=\"Das Great War Display Team mit ihren WW1 Flugzeug-Nachbauten \u00a9 Doppeladler.com\" title=\"Das Great War Display Team mit ihren WW1 Flugzeug-Nachbauten \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f35-us-15.jpg\" data-cap=\"Lockheed Martin F-35A Lightning II 15-5127 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f35-us-15.jpg\" alt=\"Lockheed Martin F-35A Lightning II 15-5127 \u00a9 Doppeladler.com\" title=\"Lockheed Martin F-35A Lightning II 15-5127 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f18-sui-4.jpg\" data-cap=\"McDonnell Douglas F\/A-18C Hornet J-5010 aus der Schweiz \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f18-sui-4.jpg\" alt=\"McDonnell Douglas F\/A-18C Hornet J-5010 aus der Schweiz \u00a9 Doppeladler.com\" title=\"McDonnell Douglas F\/A-18C Hornet J-5010 aus der Schweiz \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/frecce-20a.jpg\" data-cap=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/frecce-20a.jpg\" alt=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\" title=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-9.jpg\" data-cap=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-9.jpg\" alt=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\" title=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-10.jpg\" data-cap=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-10.jpg\" alt=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\" title=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-bel-8.jpg\" data-cap=\"Lockheed F-16 MLU &quot;Dark Falcon&quot; FA101 der belgischen Luftwaffe \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-bel-8.jpg\" alt=\"Lockheed F-16 MLU &quot;Dark Falcon&quot; FA101 der belgischen Luftwaffe \u00a9 Doppeladler.com\" title=\"Lockheed F-16 MLU &#8222;Dark Falcon&#8220; FA101 der belgischen Luftwaffe \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/bmmf-3.jpg\" data-cap=\"Lancaster Bomber mit Spitfire Begleitschutz (BBMF) \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/bmmf-3.jpg\" alt=\"Lancaster Bomber mit Spitfire Begleitschutz (BBMF) \u00a9 Doppeladler.com\" title=\"Lancaster Bomber mit Spitfire Begleitschutz (BBMF) \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/mirage-11.jpg\" data-cap=\"Dassault Mirage 2000D 3-IT Couteau Delta Display Team \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/mirage-11.jpg\" alt=\"Dassault Mirage 2000D 3-IT Couteau Delta Display Team \u00a9 Doppeladler.com\" title=\"Dassault Mirage 2000D 3-IT Couteau Delta Display Team \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/lancaster-1.jpg\" data-cap=\"Avro Lancaster B.1 Bomber PA474 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/lancaster-1.jpg\" alt=\"Avro Lancaster B.1 Bomber PA474 \u00a9 Doppeladler.com\" title=\"Avro Lancaster B.1 Bomber PA474 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/frecce-8.jpg\" data-cap=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/frecce-8.jpg\" alt=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\" title=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-16.jpg\" data-cap=\"Supermarine Spitfire LF Mk IXc - MK356 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-16.jpg\" alt=\"Supermarine Spitfire LF Mk IXc - MK356 \u00a9 Doppeladler.com\" title=\"Supermarine Spitfire LF Mk IXc &#8211; MK356 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-6.jpg\" data-cap=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-6.jpg\" alt=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\" title=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-19.jpg\" data-cap=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-19.jpg\" alt=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\" title=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc9slo-1.jpg\" data-cap=\"Pilatus PC-9M Hudournik L9-65 aus Slowenien \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc9slo-1.jpg\" alt=\"Pilatus PC-9M Hudournik L9-65 aus Slowenien \u00a9 Doppeladler.com\" title=\"Pilatus PC-9M Hudournik L9-65 aus Slowenien \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/gripen-7a.jpg\" data-cap=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/gripen-7a.jpg\" alt=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\" title=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-18.jpg\" data-cap=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-18.jpg\" alt=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\" title=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc21-1.jpg\" data-cap=\"Pilatus PC-21 G-ETPA der Firma QinetiQ \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc21-1.jpg\" alt=\"Pilatus PC-21 G-ETPA der Firma QinetiQ \u00a9 Doppeladler.com\" title=\"Pilatus PC-21 G-ETPA der Firma QinetiQ \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-17.jpg\" data-cap=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-17.jpg\" alt=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\" title=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-27.jpg\" data-cap=\"Fokker Dr1 Dreidecker Nachbau 556\/17 in der Bemalung von Leutnant Ludwig &quot;Lutz&quot; Beckmann, Jasta 6, M\u00e4rz 1918 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-27.jpg\" alt=\"Fokker Dr1 Dreidecker Nachbau 556\/17 in der Bemalung von Leutnant Ludwig &quot;Lutz&quot; Beckmann, Jasta 6, M\u00e4rz 1918 \u00a9 Doppeladler.com\" title=\"Fokker Dr1 Dreidecker Nachbau 556\/17 in der Bemalung von Leutnant Ludwig &#8222;Lutz&#8220; Beckmann, Jasta 6, M\u00e4rz 1918 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f18-ca-6.jpg\" data-cap=\"McDonnell-Douglas CF-188A Hornet 776 aus Kanada \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f18-ca-6.jpg\" alt=\"McDonnell-Douglas CF-188A Hornet 776 aus Kanada \u00a9 Doppeladler.com\" title=\"McDonnell-Douglas CF-188A Hornet 776 aus Kanada \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/puma-1.jpg\" data-cap=\"Aerospatiale SA330E Puma \/ Westland Puma HC.2 mit Kennung XW216 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/puma-1.jpg\" alt=\"Aerospatiale SA330E Puma \/ Westland Puma HC.2 mit Kennung XW216 \u00a9 Doppeladler.com\" title=\"Aerospatiale SA330E Puma \/ Westland Puma HC.2 mit Kennung XW216 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-1.jpg\" data-cap=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-1.jpg\" alt=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\" title=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/oldtimer-4.jpg\" data-cap=\"Royal Aircraft Factory BE2e Replica A2943 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/oldtimer-4.jpg\" alt=\"Royal Aircraft Factory BE2e Replica A2943 \u00a9 Doppeladler.com\" title=\"Royal Aircraft Factory BE2e Replica A2943 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/patrulla-13.jpg\" data-cap=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/patrulla-13.jpg\" alt=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\" title=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/mirage-15.jpg\" data-cap=\"Dassault Mirage 2000D des Couteau Delta Display Teams \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/mirage-15.jpg\" alt=\"Dassault Mirage 2000D des Couteau Delta Display Teams \u00a9 Doppeladler.com\" title=\"Dassault Mirage 2000D des Couteau Delta Display Teams \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-3.jpg\" data-cap=\"Supermarine Spitfire LF Mk IXc - MK356 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-3.jpg\" alt=\"Supermarine Spitfire LF Mk IXc - MK356 \u00a9 Doppeladler.com\" title=\"Supermarine Spitfire LF Mk IXc &#8211; MK356 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-14.jpg\" data-cap=\"Dassault Rafale M (6) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-14.jpg\" alt=\"Dassault Rafale M (6) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\" title=\"Dassault Rafale M (6) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-bel-9.jpg\" data-cap=\"Lockheed F-16 MLU &quot;Dark Falcon&quot; FA101 der belgischen Luftwaffe \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-bel-9.jpg\" alt=\"Lockheed F-16 MLU &quot;Dark Falcon&quot; FA101 der belgischen Luftwaffe \u00a9 Doppeladler.com\" title=\"Lockheed F-16 MLU &#8222;Dark Falcon&#8220; FA101 der belgischen Luftwaffe \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-2.jpg\" data-cap=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-2.jpg\" alt=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\" title=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/gripen-2.jpg\" data-cap=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/gripen-2.jpg\" alt=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\" title=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-pl-14.jpg\" data-cap=\"Lockheed Martin F-16C (Block 52) Fighting Falcon 4052 aus Polen \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-pl-14.jpg\" alt=\"Lockheed Martin F-16C (Block 52) Fighting Falcon 4052 aus Polen \u00a9 Doppeladler.com\" title=\"Lockheed Martin F-16C (Block 52) Fighting Falcon 4052 aus Polen \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-7.jpg\" data-cap=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-7.jpg\" alt=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\" title=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-21.jpg\" data-cap=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-21.jpg\" alt=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\" title=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-9.jpg\" data-cap=\"Supermarine Spitfire Mk XVI TE311 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-9.jpg\" alt=\"Supermarine Spitfire Mk XVI TE311 \u00a9 Doppeladler.com\" title=\"Supermarine Spitfire Mk XVI TE311 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/b2-2.jpg\" data-cap=\"Northrop Grumman B-2 Spirit &quot;Spirit of New York&quot; \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/b2-2.jpg\" alt=\"Northrop Grumman B-2 Spirit &quot;Spirit of New York&quot; \u00a9 Doppeladler.com\" title=\"Northrop Grumman B-2 Spirit &#8222;Spirit of New York&#8220; \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-10.jpg\" data-cap=\"Das Great War Display Team mit ihren WW1 Flugzeug-Nachbauten \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-10.jpg\" alt=\"Das Great War Display Team mit ihren WW1 Flugzeug-Nachbauten \u00a9 Doppeladler.com\" title=\"Das Great War Display Team mit ihren WW1 Flugzeug-Nachbauten \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/patrulla-14.jpg\" data-cap=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/patrulla-14.jpg\" alt=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\" title=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/mirage-14.jpg\" data-cap=\"Dassault Mirage 2000D 3-XY Couteau Delta Display Team \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/mirage-14.jpg\" alt=\"Dassault Mirage 2000D 3-XY Couteau Delta Display Team \u00a9 Doppeladler.com\" title=\"Dassault Mirage 2000D 3-XY Couteau Delta Display Team \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-7.jpg\" data-cap=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-7.jpg\" alt=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\" title=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/dc3-3.jpg\" data-cap=\"Douglas DC-3 \/ C-47A ZA947 des BBMF \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/dc3-3.jpg\" alt=\"Douglas DC-3 \/ C-47A ZA947 des BBMF \u00a9 Doppeladler.com\" title=\"Douglas DC-3 \/ C-47A ZA947 des BBMF \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-12.jpg\" data-cap=\"Dassault Rafale M (6) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-12.jpg\" alt=\"Dassault Rafale M (6) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\" title=\"Dassault Rafale M (6) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-8.jpg\" data-cap=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-8.jpg\" alt=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\" title=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-30.jpg\" data-cap=\"Fokker Dr1 Dreidecker Nachbau 403\/17 in den Farben von Leutnant Johann Janzen, Jasta 6, M\u00e4rz 1918 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-30.jpg\" alt=\"Fokker Dr1 Dreidecker Nachbau 403\/17 in den Farben von Leutnant Johann Janzen, Jasta 6, M\u00e4rz 1918 \u00a9 Doppeladler.com\" title=\"Fokker Dr1 Dreidecker Nachbau 403\/17 in den Farben von Leutnant  Johann Janzen, Jasta 6, M\u00e4rz 1918 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-3.jpg\" data-cap=\"Dassault Rafale M (6) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-3.jpg\" alt=\"Dassault Rafale M (6) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\" title=\"Dassault Rafale M (6) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/uav-2.jpg\" data-cap=\"Eine MQ-9B Sky Guardian flog extra aus North Dakota her\u00fcber. 2020 wird sie als Protector RG Mk.1 bei der RAF in Dienst gestellt \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/uav-2.jpg\" alt=\"Eine MQ-9B Sky Guardian flog extra aus North Dakota her\u00fcber. 2020 wird sie als Protector RG Mk.1 bei der RAF in Dienst gestellt \u00a9 Doppeladler.com\" title=\"Eine MQ-9B Sky Guardian flog extra aus North Dakota her\u00fcber. 2020 wird sie als Protector RG Mk.1 bei der RAF in Dienst gestellt \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/sentry-1.jpg\" data-cap=\"Royal Air Force Boeing E-3D Sentry AEW.1 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/sentry-1.jpg\" alt=\"Royal Air Force Boeing E-3D Sentry AEW.1 \u00a9 Doppeladler.com\" title=\"Royal Air Force Boeing E-3D Sentry AEW.1 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-7.jpg\" data-cap=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-7.jpg\" alt=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\" title=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-2.jpg\" data-cap=\"Supermarine Spitfire F.Vc - JG891 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-2.jpg\" alt=\"Supermarine Spitfire F.Vc - JG891 \u00a9 Doppeladler.com\" title=\"Supermarine Spitfire F.Vc &#8211; JG891 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/vampire-1.jpg\" data-cap=\"De Havilland Vampire T.55 LN-DHZ in den Farben der RAF WZ447 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/vampire-1.jpg\" alt=\"De Havilland Vampire T.55 LN-DHZ in den Farben der RAF WZ447 \u00a9 Doppeladler.com\" title=\"De Havilland Vampire T.55 LN-DHZ in den Farben der RAF WZ447 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-15.jpg\" data-cap=\"Royal Aircraft Factory BE2c 687 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-15.jpg\" alt=\"Royal Aircraft Factory BE2c 687 \u00a9 Doppeladler.com\" title=\"Royal Aircraft Factory BE2c 687 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-10.jpg\" data-cap=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-10.jpg\" alt=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\" title=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/patrulla-12.jpg\" data-cap=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/patrulla-12.jpg\" alt=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\" title=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-13.jpg\" data-cap=\"Supermarine Spitfire LF Mk IXc - MK356 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-13.jpg\" alt=\"Supermarine Spitfire LF Mk IXc - MK356 \u00a9 Doppeladler.com\" title=\"Supermarine Spitfire LF Mk IXc &#8211; MK356 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/uav-3b.jpg\" data-cap=\"Northrop Grumman X-47B Pegasus Demonstrator 68063 im US Navy Kleid \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/uav-3b.jpg\" alt=\"Northrop Grumman X-47B Pegasus Demonstrator 68063 im US Navy Kleid \u00a9 Doppeladler.com\" title=\"Northrop Grumman X-47B Pegasus Demonstrator 68063 im US Navy Kleid \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-31.jpg\" data-cap=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-31.jpg\" alt=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\" title=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ef-uk-6b.jpg\" data-cap=\"Eurofighter Typhoon FGR.4 ZK318 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ef-uk-6b.jpg\" alt=\"Eurofighter Typhoon FGR.4 ZK318 \u00a9 Doppeladler.com\" title=\"Eurofighter Typhoon FGR.4 ZK318 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-19.jpg\" data-cap=\"Supermarine Spitfire LF Mk IXc - MK356 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-19.jpg\" alt=\"Supermarine Spitfire LF Mk IXc - MK356 \u00a9 Doppeladler.com\" title=\"Supermarine Spitfire LF Mk IXc &#8211; MK356 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-8.jpg\" data-cap=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-8.jpg\" alt=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\" title=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-12.jpg\" data-cap=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-12.jpg\" alt=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\" title=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/static-2.jpg\" data-cap=\"Jet Provost T.3 - XM479 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/static-2.jpg\" alt=\"Jet Provost T.3 - XM479 \u00a9 Doppeladler.com\" title=\"Jet Provost T.3 &#8211; XM479 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-7.jpg\" data-cap=\"Dassault Rafale M (6) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-7.jpg\" alt=\"Dassault Rafale M (6) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\" title=\"Dassault Rafale M (6) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-1.jpg\" data-cap=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-1.jpg\" alt=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\" title=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-15.jpg\" data-cap=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-15.jpg\" alt=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\" title=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/tanker-1.jpg\" data-cap=\"Airbus A330-243 MRTT Voyager KC.2 Tanker\/Transporter ZZ330 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/tanker-1.jpg\" alt=\"Airbus A330-243 MRTT Voyager KC.2 Tanker\/Transporter ZZ330 \u00a9 Doppeladler.com\" title=\"Airbus A330-243 MRTT Voyager KC.2 Tanker\/Transporter ZZ330 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-6.jpg\" data-cap=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-6.jpg\" alt=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\" title=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-17b.jpg\" data-cap=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-17b.jpg\" alt=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\" title=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/tornado-2.jpg\" data-cap=\"Panavia Tornado GR4, ZA588 \/ 056 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/tornado-2.jpg\" alt=\"Panavia Tornado GR4, ZA588 \/ 056 \u00a9 Doppeladler.com\" title=\"Panavia Tornado GR4, ZA588 \/ 056 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-1.jpg\" data-cap=\"Supermarine Spitfire F.Vc - JG891 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-1.jpg\" alt=\"Supermarine Spitfire F.Vc - JG891 \u00a9 Doppeladler.com\" title=\"Supermarine Spitfire F.Vc &#8211; JG891 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/vampire-5.jpg\" data-cap=\"De Havilland Vampire T.55 LN-DHZ \/ WZ447 und Vampire FB-52 LN-DHY \/ VZ305\/N \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/vampire-5.jpg\" alt=\"De Havilland Vampire T.55 LN-DHZ \/ WZ447 und Vampire FB-52 LN-DHY \/ VZ305\/N \u00a9 Doppeladler.com\" title=\"De Havilland Vampire T.55 LN-DHZ \/ WZ447 und Vampire FB-52 LN-DHY \/ VZ305\/N \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/wedgetail-1.jpg\" data-cap=\"Royal Australian Air Force Boeing E-7A Wedgetail Fr\u00fchwarnflugzeug (737-7ES) A30-001 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/wedgetail-1.jpg\" alt=\"Royal Australian Air Force Boeing E-7A Wedgetail Fr\u00fchwarnflugzeug (737-7ES) A30-001 \u00a9 Doppeladler.com\" title=\"Royal Australian Air Force Boeing E-7A Wedgetail Fr\u00fchwarnflugzeug (737-7ES) A30-001 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-18.jpg\" data-cap=\"Fokker Dr1 Dreidecker Nachbau 403\/17 in den Farben von Leutnant Johann Janzen, Jasta 6, M\u00e4rz 1918 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-18.jpg\" alt=\"Fokker Dr1 Dreidecker Nachbau 403\/17 in den Farben von Leutnant Johann Janzen, Jasta 6, M\u00e4rz 1918 \u00a9 Doppeladler.com\" title=\"Fokker Dr1 Dreidecker Nachbau 403\/17 in den Farben von Leutnant  Johann Janzen, Jasta 6, M\u00e4rz 1918 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-15.jpg\" data-cap=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-15.jpg\" alt=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\" title=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-37.jpg\" data-cap=\"Royal Aircraft Factory SE-5A Replica G-BUOD B595 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-37.jpg\" alt=\"Royal Aircraft Factory SE-5A Replica G-BUOD B595 \u00a9 Doppeladler.com\" title=\"Royal Aircraft Factory SE-5A Replica G-BUOD B595 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/tucano-1.jpg\" data-cap=\"Short S-312 Tucano T1 (ZF378) ist eine Embraer EMB-312 mit st\u00e4rkerem Garrett-TPE331-Triebwerk \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/tucano-1.jpg\" alt=\"Short S-312 Tucano T1 (ZF378) ist eine Embraer EMB-312 mit st\u00e4rkerem Garrett-TPE331-Triebwerk \u00a9 Doppeladler.com\" title=\"Short S-312 Tucano T1 (ZF378) ist eine Embraer EMB-312 mit st\u00e4rkerem Garrett-TPE331-Triebwerk \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/patrulla-6.jpg\" data-cap=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/patrulla-6.jpg\" alt=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\" title=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-26.jpg\" data-cap=\"Royal Aircraft Factory BE2c 687 und Fokker Dr1 403\/17 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-26.jpg\" alt=\"Royal Aircraft Factory BE2c 687 und Fokker Dr1 403\/17 \u00a9 Doppeladler.com\" title=\"Royal Aircraft Factory BE2c 687 und Fokker Dr1 403\/17 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-32.jpg\" data-cap=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-32.jpg\" alt=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\" title=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-22.jpg\" data-cap=\"Supermarine Spitfire Mk.V AR501 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-22.jpg\" alt=\"Supermarine Spitfire Mk.V AR501 \u00a9 Doppeladler.com\" title=\"Supermarine Spitfire Mk.V AR501 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-pl-12.jpg\" data-cap=\"Lockheed Martin F-16C (Block 52) Fighting Falcon 4052 aus Polen \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/f16-pl-12.jpg\" alt=\"Lockheed Martin F-16C (Block 52) Fighting Falcon 4052 aus Polen \u00a9 Doppeladler.com\" title=\"Lockheed Martin F-16C (Block 52) Fighting Falcon 4052 aus Polen \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/frecce-22.jpg\" data-cap=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/frecce-22.jpg\" alt=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\" title=\"Frecce Tricolori auf 10x MB339 PAN (AT-339A) \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ef-static-4.jpg\" data-cap=\"Eurofighter Typhoon Mockup mit Storm Shadow Marschflugk\u00f6rper und Brimstone Panzerabwehrlenkwaffen \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ef-static-4.jpg\" alt=\"Eurofighter Typhoon Mockup mit Storm Shadow Marschflugk\u00f6rper und Brimstone Panzerabwehrlenkwaffen \u00a9 Doppeladler.com\" title=\"Eurofighter Typhoon Mockup mit Storm Shadow Marschflugk\u00f6rper und Brimstone Panzerabwehrlenkwaffen \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/gripen-12.jpg\" data-cap=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/gripen-12.jpg\" alt=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\" title=\"Saab JAS-39C Gripen 278 aus Schweden \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-34.jpg\" data-cap=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/redarrows-34.jpg\" alt=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\" title=\"Red Arrows auf BAE Systems Hawk T1 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/nh90-4.jpg\" data-cap=\"NH Industries NH90 TTH aus Finnland NH-219 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/nh90-4.jpg\" alt=\"NH Industries NH90 TTH aus Finnland NH-219 \u00a9 Doppeladler.com\" title=\"NH Industries NH90 TTH aus Finnland NH-219 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-17.jpg\" data-cap=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-17.jpg\" alt=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\" title=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-18.jpg\" data-cap=\"Supermarine Spitfire LF Mk IXc - MK356 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-18.jpg\" alt=\"Supermarine Spitfire LF Mk IXc - MK356 \u00a9 Doppeladler.com\" title=\"Supermarine Spitfire LF Mk IXc &#8211; MK356 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-11.jpg\" data-cap=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/rafale-m-11.jpg\" alt=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\" title=\"Dassault Rafale M (5) der franz\u00f6sischen Marine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-18.jpg\" data-cap=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-18.jpg\" alt=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\" title=\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-23.jpg\" data-cap=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/pc7team-23.jpg\" alt=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\" title=\"PC-7 Team der Schweizer Luftwaffe auf Pilatus PC-7 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/vampire-3.jpg\" data-cap=\"De Havilland Vampire T.55 LN-DHZ \/ WZ447 und Vampire FB-52 LN-DHY \/ VZ305\/N \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/vampire-3.jpg\" alt=\"De Havilland Vampire T.55 LN-DHZ \/ WZ447 und Vampire FB-52 LN-DHY \/ VZ305\/N \u00a9 Doppeladler.com\" title=\"De Havilland Vampire T.55 LN-DHZ \/ WZ447 und Vampire FB-52 LN-DHY \/ VZ305\/N \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/patrulla-17.jpg\" data-cap=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/patrulla-17.jpg\" alt=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\" title=\"Patrulla \u00c1guila auf CASA C 101 Aviojet \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-20.jpg\" data-cap=\"Supermarine Spitfire PR.XIX - PS915 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/spitfire-20.jpg\" alt=\"Supermarine Spitfire PR.XIX - PS915 \u00a9 Doppeladler.com\" title=\"Supermarine Spitfire PR.XIX &#8211; PS915 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/wildcat-1.jpg\" data-cap=\"AgustaWestland AW159 Wildcat HMA2 ZZ515 der Fleet Air Arm (Royal Navy) \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/wildcat-1.jpg\" alt=\"AgustaWestland AW159 Wildcat HMA2 ZZ515 der Fleet Air Arm (Royal Navy) \u00a9 Doppeladler.com\" title=\"AgustaWestland AW159 Wildcat HMA2 ZZ515 der Fleet Air Arm (Royal Navy) \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-29.jpg\" data-cap=\"Royal Aircraft Factory SE-5A Replica G-BDWJ F8010 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ww1-29.jpg\" alt=\"Royal Aircraft Factory SE-5A Replica G-BDWJ F8010 \u00a9 Doppeladler.com\" title=\"Royal Aircraft Factory SE-5A Replica G-BDWJ F8010 \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ef-formation-2.jpg\" data-cap=\"Eurofighter Typhoon der Royal Air Force \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/ef-formation-2.jpg\" alt=\"Eurofighter Typhoon der Royal Air Force \u00a9 Doppeladler.com\" title=\"Eurofighter Typhoon der Royal Air Force \u00a9 Doppeladler.com\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/chinook-1.jpg\" data-cap=\"Boeing CH-47D Chinook ZH891 \u00a9 Doppeladler.com\"><img decoding=\"async\" src=\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/chinook-1.jpg\" alt=\"Boeing CH-47D Chinook ZH891 \u00a9 Doppeladler.com\" title=\"Boeing CH-47D Chinook ZH891 \u00a9 Doppeladler.com\"><\/a><\/div>\n<p>Alle Fotos \u00a9 Doppeladler.com<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018\/\"><strong><span style=\"color: #0000ff;\">Zur\u00fcck zu Teil 1<\/span><\/strong><\/a><\/p>\n<p><strong>Weiterf\u00fchrende Links:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.airtattoo.com\/airshow\" target=\"_blank\" rel=\"noopener noreferrer\">Website der Royal International Air Tatoo &#8211; RIAT<\/a><\/li>\n<li><a href=\"https:\/\/www.doppeladler.com\/da\/misc\/riat-2011\/\">Unsere Reportage von der Royal International Air Tattoo &#8211; RIAT 2011<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Hier der 2. Teil unserer Fotoreportage von der Royal International Air Tattoo RIAT 2018 in Fairford. Ein w\u00fcrdiges Geburtstagsfest zum 100. Jahrestag der Gr\u00fcndung der Royal Air Force.<\/p>\n","protected":false},"author":1,"featured_media":13862,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[100,99,7],"tags":[973,920,74,218,504,919,216,217],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>RIAT 2018 - Fotoreportage - Teil 2 | DOPPELADLER.COM<\/title>\n<meta name=\"description\" content=\"Hier der 2. Teil unserer Fotoreportage von der Royal International Air Tattoo RIAT 2018 in Fairford. Ein w\u00fcrdiges Geburtstagsfest zum 100. Jahrestag der Gr\u00fcndung der Royal Air Force.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Doppeladler\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/\",\"url\":\"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/\",\"name\":\"RIAT 2018 - Fotoreportage - Teil 2 | DOPPELADLER.COM\",\"isPartOf\":{\"@id\":\"https:\/\/www.doppeladler.com\/da\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-6-1.jpg\",\"datePublished\":\"2018-09-30T18:04:36+00:00\",\"dateModified\":\"2019-09-01T21:04:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.doppeladler.com\/da\/#\/schema\/person\/232b998b629b89b24a916becce3e9476\"},\"description\":\"Hier der 2. Teil unserer Fotoreportage von der Royal International Air Tattoo RIAT 2018 in Fairford. Ein w\u00fcrdiges Geburtstagsfest zum 100. Jahrestag der Gr\u00fcndung der Royal Air Force.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/#primaryimage\",\"url\":\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-6-1.jpg\",\"contentUrl\":\"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-6-1.jpg\",\"width\":1600,\"height\":1200,\"caption\":\"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.doppeladler.com\/da\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RIAT 2018 &#8211; Fotoreportage &#8211; Teil 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.doppeladler.com\/da\/#website\",\"url\":\"https:\/\/www.doppeladler.com\/da\/\",\"name\":\"DOPPELADLER.COM\",\"description\":\"Plattform f\u00fcr \u00d6sterreichs Milit\u00e4rgeschichte\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.doppeladler.com\/da\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.doppeladler.com\/da\/#\/schema\/person\/232b998b629b89b24a916becce3e9476\",\"name\":\"Doppeladler\",\"sameAs\":[\"http:\/\/www.doppeladler.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RIAT 2018 - Fotoreportage - Teil 2 | DOPPELADLER.COM","description":"Hier der 2. Teil unserer Fotoreportage von der Royal International Air Tattoo RIAT 2018 in Fairford. Ein w\u00fcrdiges Geburtstagsfest zum 100. Jahrestag der Gr\u00fcndung der Royal Air Force.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/","twitter_misc":{"Verfasst von":"Doppeladler"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/","url":"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/","name":"RIAT 2018 - Fotoreportage - Teil 2 | DOPPELADLER.COM","isPartOf":{"@id":"https:\/\/www.doppeladler.com\/da\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/#primaryimage"},"image":{"@id":"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-6-1.jpg","datePublished":"2018-09-30T18:04:36+00:00","dateModified":"2019-09-01T21:04:44+00:00","author":{"@id":"https:\/\/www.doppeladler.com\/da\/#\/schema\/person\/232b998b629b89b24a916becce3e9476"},"description":"Hier der 2. Teil unserer Fotoreportage von der Royal International Air Tattoo RIAT 2018 in Fairford. Ein w\u00fcrdiges Geburtstagsfest zum 100. Jahrestag der Gr\u00fcndung der Royal Air Force.","breadcrumb":{"@id":"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/#primaryimage","url":"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-6-1.jpg","contentUrl":"https:\/\/www.doppeladler.com\/da\/wp-content\/uploads\/2018\/09\/su27-6-1.jpg","width":1600,"height":1200,"caption":"Sukhoi Su-27P Flanker 58 aus der Ukraine \u00a9 Doppeladler.com"},{"@type":"BreadcrumbList","@id":"https:\/\/www.doppeladler.com\/da\/misc\/riat-2018-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.doppeladler.com\/da\/"},{"@type":"ListItem","position":2,"name":"RIAT 2018 &#8211; Fotoreportage &#8211; Teil 2"}]},{"@type":"WebSite","@id":"https:\/\/www.doppeladler.com\/da\/#website","url":"https:\/\/www.doppeladler.com\/da\/","name":"DOPPELADLER.COM","description":"Plattform f\u00fcr \u00d6sterreichs Milit\u00e4rgeschichte","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doppeladler.com\/da\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.doppeladler.com\/da\/#\/schema\/person\/232b998b629b89b24a916becce3e9476","name":"Doppeladler","sameAs":["http:\/\/www.doppeladler.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/posts\/12991"}],"collection":[{"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/comments?post=12991"}],"version-history":[{"count":0,"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/posts\/12991\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/media\/13862"}],"wp:attachment":[{"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/media?parent=12991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/categories?post=12991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doppeladler.com\/da\/wp-json\/wp\/v2\/tags?post=12991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}